{"id":1045,"date":"2021-03-04T17:19:36","date_gmt":"2021-03-04T16:19:36","guid":{"rendered":"https:\/\/josefrancenlinea.com\/Blog\/?p=1045"},"modified":"2021-03-04T18:59:48","modified_gmt":"2021-03-04T17:59:48","slug":"la-introspeccion-y-autoconocimiento-video-de-auto-ayuda","status":"publish","type":"post","link":"https:\/\/josefrancenlinea.com\/blog\/educacion\/la-introspeccion-y-autoconocimiento-video-de-auto-ayuda\/","title":{"rendered":"La introspecci\u00f3n y autoconocimiento &#8211; Video de auto-ayuda"},"content":{"rendered":"<h1>La introspecci\u00f3n y autoconocimiento &#8211; Video de auto-ayuda.<\/h1>\n<p><iframe title=\"La introspecci\u00f3n y autoconocimiento - Video de auto-ayuda.\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/6j5a7gIG-QA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h2>La introspecci\u00f3n y autoconocimiento &#8211; Video de auto-ayuda.<\/h2>\n<p>00:00 Tal vez sea por el aislamiento al que nos obliga la pandemia, pero las \u00faltimas semanas me he sentido m\u00e1s triste, con m\u00e1s miedos, estr\u00e9s y ansiedad. Proviniendo todo ello del exterior.<\/p>\n<p>00:27 Aunque hac\u00eda mucho tiempo que no meditaba, esta situaci\u00f3n de oscuridad me ha recordado su valor. He vuelto a meditar y con ello he hecho pr\u00e1cticas de introspecci\u00f3n, an\u00e1lisis y motivaci\u00f3n. Este es un proceso maravilloso que te lleva de la oscuridad a la luz. Y que facilita la recuperaci\u00f3n de la paz y la armon\u00eda que nos son propias.<\/p>\n<p>01:05 El aforismo griego \u00abCon\u00f3cete a ti mismo\u00bb escrito en el templo de Apolo en Delfos, el siglo IV a.C. ya hac\u00eda referencia a la importancia de la introspecci\u00f3n. Con el Curso \u00abEl Poder de la Introspecci\u00f3n\u00bb en 10 PDFs, 10 Videos y 3 Bonos excelentes, te ofrezco el m\u00e9todo, sencillo, detallado y pr\u00e1ctico para que tu sol@ aprendas a conocerte m\u00e1s a ti mism@ y sentirte mejor.<\/p>\n<p>Para saber m\u00e1s, visita?: <a href=\"http:\/\/sermasfeliz.com\/auto-ayuda\/\" target=\"_blank\" rel=\"noopener\">http:\/\/sermasfeliz.com\/auto-ayuda\/<\/a><\/p>\n<p>O visita ?: <a href=\"https:\/\/josefrancenlinea.com\/elpoderdelaintrospeccion\/\" target=\"_blank\" rel=\"noopener\">https:\/\/josefrancenlinea.com\/elpoderdelaintrospeccion\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Estos son el t\u00edtulo y el primer p\u00e1rrafo de la pr\u00f3xima entrada:<\/p>\n<h3><strong>5 Formas Sencillas de Aumentar tu Autoconciencia Hoy.<\/strong><\/h3>\n<p>La autoconciencia es un concepto que inicialmente fue teorizado por Duval y Wicklund en su libro de 1972 titulado \u00abA Theory of Objective Self-Awareness\u00bb (Una teoria del autoconocimiento objetivo\u00bb. El libro teoriz\u00f3 que al centrarnos en nosotros mismos podemos desarrollar una comprensi\u00f3n m\u00e1s profunda de nuestras fortalezas y debilidades, nuestros h\u00e1bitos, nuestros valores y nuestros prop\u00f3sitos (Surban, 2020). Con este conocimiento, estamos preparados para realizar las mejoras y ajustes necesarios. Hay varias formas de mejorar la autoconciencia y este art\u00edculo describe cinco de esos m\u00e9todos.<\/p>\n<p>Para saber m\u00e1s, visita?: <a href=\"http:\/\/sermasfeliz.com\/auto-ayuda\/\" target=\"_blank\" rel=\"noopener\">http:\/\/sermasfeliz.com\/auto-ayuda\/<\/a><\/p>\n<p>O visita ?: <a href=\"https:\/\/josefrancenlinea.com\/elpoderdelaintrospeccion\/\" target=\"_blank\" rel=\"noopener\">https:\/\/josefrancenlinea.com\/elpoderdelaintrospeccion\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La introspecci\u00f3n y autoconocimiento &#8211; Video de auto-ayuda. La introspecci\u00f3n y autoconocimiento &#8211; Video de auto-ayuda. 00:00 Tal vez sea por el aislamiento al que nos obliga la pandemia, pero las \u00faltimas semanas me he sentido m\u00e1s triste, con m\u00e1s miedos, estr\u00e9s y ansiedad. Proviniendo todo ello del exterior. 00:27 Aunque hac\u00eda mucho tiempo que no meditaba, esta situaci\u00f3n de oscuridad me ha recordado su valor. He vuelto a meditar y con ello he hecho pr\u00e1cticas de introspecci\u00f3n, an\u00e1lisis y motivaci\u00f3n. Este es un proceso maravilloso que te lleva de la oscuridad a la luz. Y que facilita la recuperaci\u00f3n de la paz y la armon\u00eda que nos son propias. 01:05 El aforismo griego \u00abCon\u00f3cete a ti mismo\u00bb escrito en el templo de Apolo en Delfos, el siglo IV a.C. ya hac\u00eda referencia a la importancia de la introspecci\u00f3n. Con el Curso \u00abEl Poder de la Introspecci\u00f3n\u00bb en 10 PDFs, 10 Videos y 3 Bonos excelentes, te ofrezco el m\u00e9todo, sencillo, detallado y pr\u00e1ctico para que tu sol@ aprendas a conocerte m\u00e1s a ti mism@ y sentirte mejor. Para saber m\u00e1s, visita?: http:\/\/sermasfeliz.com\/auto-ayuda\/ O visita ?: https:\/\/josefrancenlinea.com\/elpoderdelaintrospeccion\/ &nbsp; Estos son el t\u00edtulo y el primer p\u00e1rrafo de la pr\u00f3xima entrada: 5 Formas Sencillas de Aumentar tu Autoconciencia Hoy. La autoconciencia es un concepto que inicialmente fue teorizado por Duval y Wicklund en su libro de 1972 titulado \u00abA Theory of Objective Self-Awareness\u00bb (Una teoria del autoconocimiento objetivo\u00bb. El libro teoriz\u00f3 que al centrarnos en nosotros mismos podemos desarrollar una comprensi\u00f3n m\u00e1s profunda de nuestras fortalezas y debilidades, nuestros h\u00e1bitos, nuestros valores y nuestros prop\u00f3sitos (Surban, 2020). Con este conocimiento, estamos preparados para realizar las mejoras y ajustes necesarios. Hay varias formas de mejorar la autoconciencia y este art\u00edculo describe cinco de esos m\u00e9todos. Para saber m\u00e1s, visita?: http:\/\/sermasfeliz.com\/auto-ayuda\/ O visita ?: https:\/\/josefrancenlinea.com\/elpoderdelaintrospeccion\/ &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":1048,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274],"tags":[215,216,221,223,224,212,220,222,219,213,217,218,211,214,225,226],"class_list":["post-1045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-autoconocimiento","tag-autoconocimiento-personal","tag-crecimiento-personal","tag-crecimiento-personal-actitud-positiva","tag-crecimiento-personal-motivacion","tag-introspeccion","tag-introspeccion-chojin","tag-introspeccion-como-hacer","tag-introspeccion-guiada","tag-introspeccion-personal","tag-introspeccion-psicologia","tag-introspeccion-significado","tag-introspeccion-video","tag-introspeccion-y-autoconocimiento","tag-la-introspeccion","tag-la-introspeccion-y-autoconocimiento"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/1045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=1045"}],"version-history":[{"count":0,"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/1045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/media\/1048"}],"wp:attachment":[{"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=1045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=1045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/josefrancenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=1045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}